{"id":1153,"date":"2022-04-06T10:59:37","date_gmt":"2022-04-06T10:59:37","guid":{"rendered":"https:\/\/queendentaireturquie.com\/patient-reviews\/"},"modified":"2023-08-09T06:46:09","modified_gmt":"2023-08-09T06:46:09","slug":"patient-reviews","status":"publish","type":"page","link":"https:\/\/queendentaireturquie.com\/en\/patient-reviews\/","title":{"rendered":"Patient reviews"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1153\" class=\"elementor elementor-1153 elementor-45\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0fd37e7 e-flex e-con-boxed e-con e-parent\" data-id=\"0fd37e7\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ee4ebf7 e-con-full e-flex e-con e-child\" data-id=\"ee4ebf7\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c3f193 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-elementskit-heading\" data-id=\"7c3f193\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-text_center   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title \">References<\/h2><div class=\"ekit_heading_separetor_wraper ekit_heading_elementskit-border-divider elementskit-style-long\"><div class=\"elementskit-border-divider elementskit-style-long\"><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9d6ce41 e-con-full e-flex e-con e-child\" data-id=\"9d6ce41\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d3b3586 e-flex e-con-boxed e-con e-child\" data-id=\"d3b3586\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc9c6b3 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"fc9c6b3\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1600\" height=\"942\" src=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/tankaua.jpg\" class=\"attachment-full size-full wp-image-2617\" alt=\"\" srcset=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/tankaua.jpg 1600w, https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/tankaua-300x177.jpg 300w, https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/tankaua-1024x603.jpg 1024w, https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/tankaua-768x452.jpg 768w, https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/tankaua-1536x904.jpg 1536w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">MME. TANKOUA (ITALY)<\/h3><p class=\"elementor-image-box-description\">Merci pour l\u2019extraordinaire travaille que vous avez fait, le service et l\u2019accompagnement tout au long de la semaine \u00e9taient parfaits, tous les conseille que vous ayez pu me donner. Merci \u00e0 toute l\u2019\u00e9quipe qui est comp\u00e9tente et professionnelle, la clinique et le mat\u00e9riel sont tr\u00e8s modernes et une propret\u00e9 irr\u00e9prochable encore merci pour tout. J\u2019ai pass\u00e9 un s\u00e9jour incroyable et le r\u00e9sultat est plus que tr\u00e8s bien merci beaucoup je recommande avec un grand plaisir !<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca3e738 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"ca3e738\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"417\" height=\"500\" src=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/jabeur.jpg\" class=\"attachment-full size-full wp-image-2631\" alt=\"\" srcset=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/jabeur.jpg 417w, https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/jabeur-250x300.jpg 250w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">MR. JABEUR (MAROC, CASABLANCA)<\/h3><p class=\"elementor-image-box-description\">Bonjour MessieursPourqoui J\u2019 ai choisi Queen Dentaire ?C\u2019est tout simplement Parce que j\u2019ai trouv\u00e9 une r\u00e9activit\u00e9 tr\u00e8s professionelle \u00e0 mes besoins.Le contact est \u00e9tablie, J\u2019ai eu des r\u00e9ponses satisfaisantes \u00e0 toutes mes questions.A la lumi\u00e8re d\u2019une radio panoramique des propositions ont \u00e9te faites et un devis approximatif \u00e0 \u00e9t\u00e9 \u00e9tabli.Rassur\u00e9 par le professionalisme et la disponibilit\u00e9 Umut m\u00eame \u00e0 des heures tardives la nuit, je n\u2019ai pas h\u00e9sit\u00e9 un moment \u00e0 faire ma valise direction Queen Dentaire \u00e0 Antalya.Arriv\u00e9e tr\u00e8s tard \u00e0 l\u2019aeroport Mr Riza m\u2019a accueilli agr\u00e9ablement et direction l\u2019h\u00f4tel.Chemin faisant il me rassure et me brief sur la clinique et ses prestations et mon programme de soins durant mon s\u00e9jour.Le lendemain \u00e0 mon arriv\u00e9e \u00e0 la clinique j\u2019\u00e9tais surpris agr\u00e9ablement en d\u00e9couvrant un \u00e9tablissement aux normes internationales propres, le staff souriant et accueillant et un mat\u00e9riel de pointe.Je suis rassur\u00e9 au fond de moi m\u00eame qui a une phobie des dentistes.Pris en charge par le docteur Bilgin Bilgili et ses collaborateurs.Les soins ont commenc\u00e9s avec minutie et professionalisme pour toute ma dentition.Gr\u00e2ce \u00e0 la dext\u00e9rit\u00e9 et la minutie du docteur Bilgin, les soignantes et l\u2019assistance permanente est efficace Umut qui traduit au fur et \u00e0 mesure les \u00e9tapes des soinsLes implants et les dents sont fix\u00e9s, les contr\u00f4les sont faits.R\u00e9sultat tr\u00e8s satisfaisant le sourire est revenu mieux qu\u2019avant.Merci beaucoup \u00e0 toutes et \u00e0 tous ceux qui ont contribu\u00e9 \u00e0 me rendre mon sourire.Pour faire vos soins je vous recommande de les faire chez Queen Dentaire \u00e0 Antalya. Vous ne serez pas d\u00e9\u00e7u.Amicalement votreCheikh Jabeur (Maroc)<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-492762e elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"492762e\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"417\" height=\"500\" src=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/benjemai.jpg\" class=\"attachment-full size-full wp-image-2634\" alt=\"\" srcset=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/benjemai.jpg 417w, https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/benjemai-250x300.jpg 250w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">MME. BENJEMAI (FRANCE, PARIS)<\/h3><p class=\"elementor-image-box-description\">Par ce message je profite encore pour vous remercier du fond du c\u0153ur, pour votre disponibilit\u00e9, amabilit\u00e9 et professionnalisme !<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-978def5 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"978def5\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"500\" src=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/slimane.jpg\" class=\"attachment-full size-full wp-image-2637\" alt=\"\" srcset=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/slimane.jpg 417w, https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/slimane-250x300.jpg 250w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">MR. SLIMANE (BELGIUM)<\/h3><p class=\"elementor-image-box-description\">You work well, the result is amazing! Thank you very much to all the team!<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96193bc elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"96193bc\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"500\" src=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/ruben.jpg\" class=\"attachment-full size-full wp-image-2664\" alt=\"\" srcset=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/ruben.jpg 417w, https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/ruben-250x300.jpg 250w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">MR. RUBEN (BELGIQUE)<\/h3><p class=\"elementor-image-box-description\">Merci \u00e0 toute \u00e9quipe Queen Dentaire, du d\u00e9but \u00e0 la fin et \u00e0 votre professionnalisme qui nous donne confiance. Merci \u00e0 Umut, sa disponibilit\u00e9 envers les patients, merci \u00e0 Riza qui nous rencontre tout le temps, Gunay pour sa gentillesse et bien s\u00fbr \u00e0 Dr. Bilgin pour le travail soigneusement effectu\u00e9 !<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22412f7 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"22412f7\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"500\" src=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/jamal.jpg\" class=\"attachment-full size-full wp-image-2730\" alt=\"\" srcset=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/jamal.jpg 417w, https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/jamal-250x300.jpg 250w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">MR. JAMAL ZOUGARI (BELGIQUE)<\/h3><p class=\"elementor-image-box-description\">Bonjour Umut et toute l\u2019\u00e9quipe,Juste pour vous dire que malgr\u00e9 la douleur des premiers jours de mon s\u00e9jour en Turquie, je suis rentr\u00e9e en Belgique et vraiment satisfaite du r\u00e9sultat.Depuis que je suis rentr\u00e9e, je n\u2019ai aucune douleur, c\u2019est vraiment incroyable!!!Je pense vous envoyer des patients car ils sont tr\u00e8s \u00e9tonn\u00e9s du r\u00e9sultat Cliquez-moi!Encore un tout grand merci pour votre gentillesse Cliquez-moi!<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41dc397 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"41dc397\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"249\" src=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2022\/04\/ab-300x249-1.jpeg\" class=\"attachment-full size-full wp-image-960\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">MOHAMED RAOURAOUA, PR\u00c9SIDENT DE LA F\u00c9D\u00c9RATION ALG\u00c9RIENNE DE FOOTBALL (ALG\u00c9RIE)<\/h3><p class=\"elementor-image-box-description\">Bonjour, Docteur, Umut et Semir,Je vous remercie beaucoup pour l\u2019accueil chaleureux et surtout l\u2019efficacit\u00e9 dans le travail.Je remercie beaucoup le docteur encore une fois pour sa disponibilit\u00e9 le dimanche.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29a8637 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"29a8637\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"500\" src=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/CarolinePascal.jpg\" class=\"attachment-full size-full wp-image-2667\" alt=\"\" srcset=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/CarolinePascal.jpg 417w, https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/CarolinePascal-250x300.jpg 250w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">CAROLINE ET PASCAL MARTIN (FRANCE, PARIS)<\/h3><p class=\"elementor-image-box-description\">Bonjour, Umut et Semir,Nous voulions vraiment vous remercier car d\u00e8s notre arriv\u00e9e \u00e0 Antalya jusqu\u2019\u00e0 notre d\u00e9part, votre accueil, votre gentillesse et votre aide chaque jour, ont \u00e9t\u00e9 irr\u00e9prochables.Merci \u00e9galement au travail exemplaire de votre dentiste, qui est un excellent professionnel.Nous repartons donc ravis d\u2019avoir choisi Queen dentaire pour notre sourire et le recommandons \u00e0 tous<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3666d4e elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"3666d4e\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"500\" src=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/Combeauya.jpg\" class=\"attachment-full size-full wp-image-2670\" alt=\"\" srcset=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/Combeauya.jpg 417w, https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/Combeauya-250x300.jpg 250w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">MR. COMBEAU (FRANCE, NANCY)<\/h3><p class=\"elementor-image-box-description\">Mesdames, messieurs,<br>Tout d\u2019abord merci, merci pour tout. J\u2019\u00e9num\u00e8re les satisfactions :<br>\u2013 les soins parfaits comme je l\u2019attendais<br>\u2013 Umut grande organisatrice, grande assistante, toujours pr\u00e9sente pour la traduction<br>\u2013 Riza, le chauffeur, tr\u00e8s sympathique et toujours \u00e0 l\u2019heure<br>\u2013 Docteur tr\u00e8s efficace, tr\u00e8s calme et rassurant<br>\u2013 tout le reste du personnel dont je ne sais pas le nom<br>\u2013 le prix : un tiers du prix en France malgr\u00e9 les autres frais comme l\u2019avion et l\u2019h\u00e9bergement<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77514c3 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"77514c3\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"500\" src=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/helene.jpg\" class=\"attachment-full size-full wp-image-2733\" alt=\"\" srcset=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/helene.jpg 417w, https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/helene-250x300.jpg 250w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">H\u00c8L\u00c8NE L. (FRANCE)<\/h3><p class=\"elementor-image-box-description\">Comme beaucoup je suis arriv\u00e9e ici avec un peu d\u2019appr\u00e9hension mais mes doutes se sont vite estompes, une \u00e9quipe d\u2019une gentillesse et d\u2019un professionnalisme sans faille, je suis plus que ravie du r\u00e9sultat. Un \u00e9norme merci aux docteurs Bilgin et Alican pour leur professionnalisme et sa patience, Riza (\u00e0 qui j\u2019ai bien failli broy\u00e9 la main), Umut et Semir pour leur \u00e9coute et leur soutien.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5c9791 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"d5c9791\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"500\" src=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/mme-1.jpg\" class=\"attachment-full size-full wp-image-2742\" alt=\"\" srcset=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/mme-1.jpg 417w, https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/mme-1-250x300.jpg 250w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">MME ANNE-FRAN\u00c7OISE M. (BELGIQUE)<\/h3><p class=\"elementor-image-box-description\">J\u2019ai contact\u00e9 la clinique Queen dentaire au mois d\u2019ao\u00fbt 2014 car j\u2019en \u00e9tais arriv\u00e9e \u00e0 un point o\u00f9 je n\u2019osais plus sourire, rire aux \u00e9clats, alors que j\u2019adore \u00e7a.J\u2019ai \u00e9t\u00e9 accueillie au t\u00e9l\u00e9phone par une personne formidable, pr\u00e9venante, accueillante et tr\u00e8s professionnelle. Rendez-vous a \u00e9t\u00e9 pris pour le mois suivant, de telle mani\u00e8re que je puisse b\u00e9n\u00e9ficier de tarifs avantageux, tant pour les vols que les h\u00f4tels. Le diagnostic a \u00e9t\u00e9 pour ma part assez lourd\u2026 d\u00e9chaussement de la plupart de mes dents, ce qui les rendait mobiles\u2026 Et plus beaucoup de structure osseuse pour accueillir d\u2019\u00e9ventuels implants.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-525d94e elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"525d94e\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"500\" src=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/mr-zakarial.jpg\" class=\"attachment-full size-full wp-image-2673\" alt=\"\" srcset=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/mr-zakarial.jpg 417w, https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/mr-zakarial-250x300.jpg 250w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">MR. ZAKARIA L. (FRANCE)<\/h3><p class=\"elementor-image-box-description\">Bonjour,Je voulais remercier de tout c\u0153ur du temps et de l\u2019intention que vous avez su m\u2019apporter \u00e0 vous ainsi que toutes l\u2019\u00e9quipe.Vous avez su m\u2019apporter le soutien et le soulagement que j\u2019esp\u00e9rais alors que j\u2019avais beaucoup d\u2019incertitudes sur mes dents.Encore tous mes remerciements pour l\u2019accueil et le professionnalisme de toutes l\u2019\u00e9quipe Queen Denatire.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76265f7 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"76265f7\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"500\" src=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/MISS-J.jpg\" class=\"attachment-full size-full wp-image-2757\" alt=\"\" srcset=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/MISS-J.jpg 417w, https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/MISS-J-250x300.jpg 250w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">MISS. J. (COMING ILE DE FRANCE)<\/h3><p class=\"elementor-image-box-description\">I would like to thank Umut and Riza and the whole team for your professionalism and patience and especially for listening to my needs throughout my stay. You were adorable to me, good advice and above all no stress. The clinic is very classy, \u200b\u200bthe material of high quality and the latest technologies. The dentist is very professional, he did a good job. Actions performed: care, crowns, bleaching.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-772ff3c elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"772ff3c\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"500\" src=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/celine.jpg\" class=\"attachment-full size-full wp-image-2745\" alt=\"\" srcset=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/celine.jpg 417w, https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/celine-250x300.jpg 250w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">MLLE C\u00c9LINE D. (FRANCE, PARIS)<\/h3><p class=\"elementor-image-box-description\">Je suis arriv\u00e9e en Turquie avec quelque appr\u00e9hension sur le d\u00e9rouler et le r\u00e9sultat, je suis assez exigeante dans la vie en g\u00e9n\u00e9rale. Arriver comme une princesse ils s\u2019occupent de venir vous chercher, vous accompagnent \u00e0 chaque \u00e9tape m\u00eame la o\u00f9 vous ne voyez aucun d\u00e9faut ils peuvent encore am\u00e9liorer un service. Qualit\u00e9 de soins c\u2019est la premi\u00e8re qualit\u00e9. Quand \u00e0 la d\u00e9couverte de votre premier sourire une \u00e9motion tellement grande que des larmes viens c\u2019est simplement magique l\u2019insertion avec mon visage et c\u2019est parfait !<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-921f696 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"921f696\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"500\" src=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/queen-1.jpg\" class=\"attachment-full size-full wp-image-2748\" alt=\"\" srcset=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/queen-1.jpg 417w, https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/queen-1-250x300.jpg 250w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">MR. PIERRE GUYARD (FRANCE, PARIS)<\/h3><p class=\"elementor-image-box-description\">Tout va tr\u00e8s bien, j\u2019ai retrouv\u00e9 le plaisir de manger normalement. Et les dents sont magnifiques! Je dois vous dire aussi que je ne regrette pas une seconde d\u2019avoir choisi votre clinique pour les soins. Je vous remercie pour votre gentillesse et votre accompagnement, toujours disponible et toujours de bonne humeur. Je remercie aussi le chirurgien qui s\u2019est occup\u00e9 de moi et dont le travail est remarquable. Certes, passer deux semaines \u00e0 Antalya, c\u2019est beaucoup et nous connaissons maintenant tr\u00e8s bien cette ville, mais \u00e7a valait vraiment la peine et le r\u00e9sultat final est parfait. Voil\u00e0 si c\u2019\u00e9tait \u00e0 refaire, nous choisirions tout de suite Queen Dentaire !<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc4741f elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"bc4741f\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"500\" src=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/08\/monsi.jpg\" class=\"attachment-full size-full wp-image-2812\" alt=\"\" srcset=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/08\/monsi.jpg 417w, https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/08\/monsi-250x300.jpg 250w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">MONSIEUR ET MADAME BELLENOT (SUISSE)<\/h3><p class=\"elementor-image-box-description\">Nous vous remercions encore pour tout mon papa et moi sommes tr\u00e8s content du travail effectu\u00e9. Tout \u00e9tait tr\u00e8s bien organis\u00e9 : l\u2019accueil \u00e0 l\u2019a\u00e9roport, le transport, l\u2019accompagnement, les rendez-vous chez le docteur et toutes les explications, le traitement. Toujours ponctuel, aimable et ce qui est le plus important tr\u00e8s efficace, le r\u00e9sultat est vraiment tr\u00e8s beau ! Merci encore une fois !<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0c3bcb elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"b0c3bcb\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"500\" src=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/chris.jpg\" class=\"attachment-full size-full wp-image-2760\" alt=\"\" srcset=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/chris.jpg 417w, https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/07\/chris-250x300.jpg 250w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">CHRIS (FRANCE)<\/h3><p class=\"elementor-image-box-description\">Je suis venue seule a Antalya une semaine pour y effectuer mes soins \u00e0 Queen Dentaire. J\u2019ai h\u00e9sit\u00e9 avant de prendre mon billet car je ne savais pas \u00e0 quoi m\u2019attendre mais finalement mon s\u00e9jour dans la clinique s\u2019est tr\u00e8s bien pass\u00e9 ! Plus que je ne l\u2019esp\u00e9rais ! L\u2019\u00e9quipe est tr\u00e8s \u00e0 l\u2019\u00e9coute de nos besoins et nos souhaits durant toute la dur\u00e9e des soins. Ils offrent vraiment un tr\u00e8s bon suivi et accompagnement et r\u00e9pondent \u00e0 tous nos doutes et questions. Je ne regrette pas un seul instant d\u2019\u00eatre venue. La clinique est tr\u00e8s moderne, le mat\u00e9riel de haute qualit\u00e9 et ils utilisent les derni\u00e8res technologies. La dentiste a fait un travail tout simplement exceptionnel. Elle est tr\u00e8s professionnelle, calme et gentille. Je ne le remercierai jamais assez ainsi que les techniciens qui travaillent tr\u00e8s minutieusement pour la pr\u00e9paration des implants et couronnes. Grace \u00e0 Queen Dentaire j\u2019ai un nouveau sourire et je suis vraiment tr\u00e8s tr\u00e8s contente du r\u00e9sultat. Je souris tout le temps . Par ailleurs les Turques sont tr\u00e8s accueillants et la nourriture tr\u00e8s bonne ! Franchement n\u2019h\u00e9sitez plus, venez \u00e0 Queen Dentaire vous ne serez pas d\u00e9\u00e7us. Vraiment pas!<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b577d1f elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"b577d1f\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">MME JOELLE<\/h3><p class=\"elementor-image-box-description\">Juste un petit mot pour vous remercier pour votre accueil. Nous avons appr\u00e9cie votre gentillesse et votre professionnalisme ainsi que les grandes comp\u00e9tences des praticiens avec qui vous travaillez. Encore merci!<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a985f0 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"1a985f0\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"500\" src=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/08\/alexis.jpg\" class=\"attachment-full size-full wp-image-2815\" alt=\"\" srcset=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/08\/alexis.jpg 417w, https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/08\/alexis-250x300.jpg 250w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">MR. ALEXIS BUISSON (FRANCE)<\/h3><p class=\"elementor-image-box-description\">Les soins avec \u00ab Queen Dentaire \u00bb en Turquie \u00e0 Antalya Pour refaire vos dents pas cher voici donc l\u2019adresse que j\u2019ai test\u00e9 pour vous. J\u2019\u00e9cris cet article pour que vous ayez un t\u00e9moignage ind\u00e9pendant. Toute l\u2019\u00e9quipe m\u00e9dicale est turque et tr\u00e8s comp\u00e9tente. L\u2019accueil est assur\u00e9 par Umut, une aimable jeune femme qui parle tr\u00e8s bien fran\u00e7ais et anglais. Tout commence par une tasse de caf\u00e9, un scanner panoramique de la derni\u00e8re g\u00e9n\u00e9ration et le RDV avec le docteur \u2013 \u201cbig boss\u201d. Une fois d\u00e9termin\u00e9 avec lui les travaux \u00e0 faire (ils sont tr\u00e8s corrects ne vous incitant jamais \u00e0 en faire plus qu\u2019il ne faut), le devis est d\u00e9termin\u00e9 pr\u00e9cis\u00e9ment. Les choses s\u00e9rieuses peuvent commencer. J\u2019ai pass\u00e9 6 heures sur cette chaise pour arracher 7 dents et en limer 16! Mais en 5 jours et 1\/3 du prix ils ont fait ce qui aurait pris un an en France\u2026 Tout est garanti 5 ans !!!! Allez salut, au moins maintenant je peux vous sourire !!! 09.07.2011<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-825e72d elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"825e72d\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">MLLE ROJO (FRANCE)<\/h3><p class=\"elementor-image-box-description\">Au d\u00e9but j\u2019ai eu peur de venir, franchement. Mais quand je suis arriv\u00e9e dans la clinique j\u2019\u00e9tais tr\u00e8s bien surprise en positif bien s\u00fbr. Le mat\u00e9riel \u00e9tait l\u00e0 comme en France. L\u2019accueil c\u2019\u00e9tait tr\u00e8s bien, il y avait les accompagnateurs francophone, \u00e7a m\u2019a aid\u00e9 beaucoup. Je suis tr\u00e8s contente du r\u00e9sultat, que vous pouvez voir et estimer!<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd4ef2b elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"dd4ef2b\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">MME S. VALZER, MR C. RUCKERT (FRANCE, CANNES)<\/h3><p class=\"elementor-image-box-description\">J\u2019avais de gros probl\u00e8mes dentaires et j\u2019ai visit\u00e9 beaucoup de cliniques. J\u2019ai connu Queen Dentaire par Internet. Avant de venir j\u2019ai eu toutes les informations n\u00e9cessaires ce qui \u00e9tait tr\u00e8s rassurant. Aucune mauvaise surprise! Umut et Riza le chauffeur sont aux petits soins pour nous. Le r\u00e9sultat\u2026 parfait! Rien \u00e0 dire! Tous, l\u2019\u00e9quipe de cette clinique, ils sont devenus nos amis !<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00b0bf9 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"00b0bf9\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"417\" height=\"500\" src=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/08\/emanuel.jpg\" class=\"attachment-full size-full wp-image-2818\" alt=\"\" srcset=\"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/08\/emanuel.jpg 417w, https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2023\/08\/emanuel-250x300.jpg 250w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">MR. EMMANUEL (SUISSE, GEN\u00c8VE)<\/h3><p class=\"elementor-image-box-description\">Je suis venu \u00e0 Antalya au mois de mai pour me refaire enti\u00e8rement les dents. Apr\u00e8s avoir pris contact par Internet et par t\u00e9l\u00e9phone j\u2019ai \u00e9t\u00e9 convaincu que c\u2019\u00e9tait la meilleure mani\u00e8re de r\u00e9gler ce probl\u00e8me une fois pour tout.J\u2019ai \u00e9t\u00e9 pris en charge directement \u00e0 l\u2019a\u00e9roport et la charmante Umut qui m\u2019a emmen\u00e9 \u00e0 l\u2019h\u00f4tel. Le lendemain nous sommes all\u00e9s chez le dentiste (une clinique \u00e0 la pointe de la technologie), confirm\u00e9 le devis pr\u00e9\u00e9tabli sur Internet et commenc\u00e9 les soins.Tout s\u2019est tr\u00e8s bien pass\u00e9, pas de douleurs et apr\u00e8s quelques jours j\u2019ai retrouv\u00e9 mon sourire perdu depuis des ann\u00e9es !Ceci sans compter le cadre magnifique et le d\u00e9paysement. De plus le prix est sans concurrence avec les prix exorbitants en Suisse (environ 4 \u00e0 5 x moins cher) sans compter la rapidit\u00e9 et la qualit\u00e9 des produits.Si vous n\u2019aimez pas particuli\u00e8rement aller chez le dentiste, je vous recommande sans h\u00e9siter de venir refaire les dents chez Queen Dentaire. Cela en vaut la peine et le r\u00e9sultat vous enchantera!<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>References MME. TANKOUA (ITALY) Merci pour l\u2019extraordinaire travaille que vous avez fait, le service et l\u2019accompagnement tout au long de la semaine \u00e9taient parfaits, tous les conseille que vous ayez pu me donner. Merci \u00e0 toute l\u2019\u00e9quipe qui est comp\u00e9tente et professionnelle, la clinique et le mat\u00e9riel sont tr\u00e8s modernes et une propret\u00e9 irr\u00e9prochable encore [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-1153","page","type-page","status-publish","hentry"],"rankMath":{"parentDomain":"queendentaireturquie.com","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"The featured image should be at least 200 by 200 pixels to be picked up by Facebook and other social media sites.","pluginReviewed":false,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"patient-reviews","permalinkFormat":"https:\/\/queendentaireturquie.com\/en\/%pagename%\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/queendentaireturquie.com\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":true,"primaryTaxonomy":false,"serpData":{"title":"","description":"","focusKeywords":"","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"username","primaryTerm":0,"authorName":"queendentaire","titleTemplate":"%title% %sep% %sitename%","descriptionTemplate":"%excerpt%","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["a cut above","absolute","absolutely","absolutely lowest","absurd","abuse","accurate","accuse","achieve","actionable","adaptable","adequate","admit","adorable","advantage","advice","affordable","aggravate","aggressive","agitated","agonizing","agony","alarmed","alarming","alienated","aligned","alive","all-inclusive","alluring","always","amazing","amp","animated","annihilate","announcing","anonymous","antagonistic","anxious","apocalypse","appalled","approved","approving","argumentative","armageddon","arrogant","ass kicking","assault","assured","astonishing","astounded","astounding","at ease","atrocious","attack","attractive","audacity","authentic","authoritative","authority","avoid","aware","awe-inspiring","awesome","awkward","backbone","backdoor","backed","backlash","backstabbing","badass","balanced","banned","bargain","barrage","basic","battle","beaming","beat down","beating","beautiful","beauty","begging","behind the scenes","belief","belong","best","best-selling","better","beware","big","billion","black market","blacklisted","blast","blessed","blinded","blissful","blood","bloodbath","bloodcurdling","bloody","blunder","blushing","bold","bomb","bona","bona fide","bonanza","bonus","bootleg","bottom line","bountiful","brave","bravery","brazen","break","breaking","breakthrough","breathtaking","bright","brilliant","broke","brutal","budget","buffoon","bullshit","bully","bumbling","buy","cadaver","calm","cancel anytime","capable","captivate","captivating","carefree","case study","cash","cataclysmic","catapult","catastrophe","caution","censored","centered","certain","certainly","certified","challenge","charming","cheap","cheat","cheat-sheet","cheer","cheerful","child-like","clarity","classified","clear","clueless","collapse","colorful","colossal","comfortable","compare","competitive","complete","completely","completeness","comprehensive","compromise","compulsive","concealed","conclusive","condemning","condescending","confess","confession","confessions","confident","confidential","conquer","conscientious","constructive","content","contrary","controlling","controversial","convenient","convert","cool","cooperative","copy","corpse","corrupt","corrupting","courage","courageous","cover-up","covert","coward","cowardly","crammed","crave","crazy","create","creative","cringeworthy","cripple","crisis","critical","crooked","crush","crushing","damaging","danger","dangerous","daring","dazzling","dead","deadline","deadly","death","decadent","deceived","deceptive","deep","defiance","definitely","definitive","defying","dejected","delicious","delight","delighted","delightful","delirious","delivered","demoralizing","deplorable","depraved","desire","desperate","despicable","destiny","destroy","detailed","devastating","devoted","diagnosed","direct","dirty","disadvantages","disastrous","discount","discover","disdainful","disempowered","disgusted","disgusting","dishonest","disillusioned","disoriented","distracted","distraught","distressed","distrustful","divulge","document","dollar","dominate","doomed","double","doubtful","download","dreadful","dreamy","drive","drowning","dumb","dynamic","eager","earnest","easily","easy","economical","ecstatic","edge","effective","efficient","effortless","elated","eliminate","elite","embarrass","embarrassed","embarrassing","emergency","emerging","emphasize","empowered","enchant","encouraged","endorsed","energetic","energy","enormous","enraged","enthusiastic","envy","epic","epidemic","essential","ethical","euphoric","evil","exactly","exasperated","excellent","excited","excitement","exciting","exclusive","exclusivity","excruciating","exhilarated","expensive","expert","explode","exploit","explosive","exposed","exquisite","extra","extraordinary","extremely","exuberant","eye-opening","fail","fail-proof","failure","faith","famous","fantasy","fascinating","fatigued","faux","faux pas","fearless","feast","feeble","festive","fide","fierce","fight","final","fine","fired","first","first ever","flirt","fluid","focus","focused","fool","fooled","foolish","forbidden","force-fed","forever","forgiving","forgotten","formula","fortune","foul","frantic","free","freebie","freedom","frenzied","frenzy","frightening","frisky","frugal","frustrated","fulfill","fulfilled","full","fully","fun","fun-loving","fundamentals","funniest","funny","furious","gambling","gargantuan","genius","genuine","gift","gigantic","giveaway","glamorous","gleeful","glorious","glowing","goddamn","gorgeous","graceful","grateful","gratified","gravity","great","greatest","greatness","greed","greedy","gripping","grit","grounded","growth","guaranteed","guilt","guilt-free","gullible","guts","hack","happiness","happy","harmful","harsh","hate","have you heard","havoc","hazardous","healthy","heart","heartbreaking","heartwarming","heavenly","hell","helpful","helplessness","hero","hesitant","hidden","high tech","highest","highly effective","hilarious","hoak","hoax","honest","honored","hope","hopeful","horribly","horrific","horrifying","horror","hostile","how to","huge","humility","humor","hurricane","hurry","hypnotic","idiot","ignite","illegal","illusive","imagination","immediately","imminently","impatience","impatient","impenetrable","important","impressive","improved","in the zone","incapable","incapacitated","incompetent","inconsiderate","increase","incredible","indecisive","indulgence","indulgent","inexpensive","inferior","informative","infuriated","ingredients","innocent","innovative","insane","insecure","insider","insidious","inspired","inspiring","instant savings","instantly","instructive","insult","intel","intelligent","intense","interesting","intriguing","introducing","invasion","investment","iron-clad","ironclad","irresistible","irs","is here","jackpot","jail","jaw-dropping","jealous","jeopardy","jittery","jovial","joyous","jubilant","judgmental","jumpstart","just arrived","keen","kickass","kickstart","kill","killed","killing","kills","know it all","lame","largest","lascivious","last","last chance","last minute","latest","laugh","laughing","launch","launching","lavishly","lawsuit","lazy","left behind","legendary","legitimate","liberal","liberated","lick","lies","life-changing","lifetime","light","lighthearted","likely","limited","literally","little-known","loathsome","lonely","looming","loser","lost","love","lucrative","lunatic","lurking","lust","luxurious","luxury","lying","magic","magical","magnificent","mainstream","malicious","mammoth","manipulative","marked down","massive","master","masterclass","maul","mediocre","meditative","meltdown","memorability","memorable","menacing","mesmerizing","meticulous","mind-blowing","minimalist","miracle","mired","mischievous","misgiving","missing out","mistake","monetize","money","moneyback","moneygrubbing","monumental","most important","motivated","mouth-watering","murder","mystery","nail","naked","natural","naughty","nazi","nest egg","never","new","nightmare","no good","no obligation","no one talks about","no questions asked","no risk","no strings attached","non-controlling","noted","novelty","now","obnoxious","obsessed","obsession","obvious","odd","off-kilter","off-limits","off-the record","offensive","official","okay","on-demand","open-minded","opportunities","optimistic","ordeal","outlawed","outrageousness","outstanding","overcome","overjoyed","overnight","overwhelmed","packed","painful","painless","painstaking","pale","panic","panicked","paralyzed","pas","passionate","pathetic","pay zero","payback","perfect","peril","perplexed","perspective","pessimistic","pioneering","piranha","pitfall","pitiful","placid","plague","played","playful","pleased","pluck","plummet","plunge","poison","poisonous","polarizing","poor","popular","portfolio","pound","powerful","powerless","practical","preposterous","prestige","price","priceless","pride","prison","privacy","private","privileged","prize","problem","productive","professional","profit","profitable","profound","promiscuous","promising","promote","protect","protected","proven","provocative","provoke","psychological","pummel","punch","punish","pus","quadruple","quality","quarrelsome","quick","quick-start","quickly","quiet","radiant","rare","ravenous","rebellious","recession-proof","reckoning","recognized","recommend","recreate","reduced","reflective","refugee","refund","refundable","reject","relaxed","release","relentless","reliable","remarkable","replicate","report","reprimanding","repulsed","repulsive","research","resentful","resourceful","responsible","responsive","rested","restricted","results","retaliating","reveal","revealing","revenge","revengeful","revisited","revolting","revolutionary","reward","rich","ridiculous","risky","riveting","rookie","rowdy","ruin","rules","ruthless","sabotaging","sacred","sadistic","sadly","sadness","safe","safety","sale","sampler","sarcastic","satisfied","savage","savagery","save","savings","savvy","scam","scandal","scandalous","scarce","scared","scary","scornful","scream","searing","secret","secret agenda","secret plot","secrets","secure","security","seductive","seething","seize","selected","self-hating","self-sufficient","sensational","senseless","sensual","serene","seriously","severe","sex","sexy","shaking","shameful","shameless","shaming","shatter","shellacking","shocking","should","shrewd","sick and tired","signs","silly","simple","simplicity","simplified","simplistic","sincere","sinful","sins","six-figure","sizable","sizzle","sizzled","sizzles","sizzling","sizzlingly","skill","skyrocket","slaughter","slave","sleazy","sleeping","sly","smash","smiling","smug","smuggle","smuggled","sneak-peek","sneaky","sniveling","snob","snooty","snotty","soar","soaring","solid","solution","spank","special","spectacular","speedy","spell-binding","spine","spirit","spirited","spiteful","spoiler","spontaneous","spotlight","spunky","squirming","stable","staggering","startling","steady","steal","stealthy","steamy","step-by-step","still","stoic","stop","strange","strangle","strategy","stressed","strong","strongly suggest","struggle","stuck up","studies","stunning","stupid","stupid-simple","sturdy","sublime","succeed","success","successful","suck","suddenly","suffer","sunny","super","super-human","superb","supercharge","superior","supported","supportive","sure","sure fire","surefire","surge","surging","surprise","surprised","surprising","survival","survive","suspicious","sweaty","swoon","swoon-worthy","tailspin","tank","tantalizing","targeted","tawdry","tease","technology","teetering","tempting","tenacious","tense","terrible","terrific","terrified","terrifying","terror","terrorist","tested","thankful","the truth","threaten","threatened","thrilled","thrilling","thug","ticked off","tickled","timely","today","torture","toxic","track record","trade secret","tragedy","tragic","transform","transparency","trap","trapped","trauma","traumatized","treacherous","treasure","tremendous","trend","tricks","triggers","triple","triumph","truly","trusting","trustworthy","truth","truthful","turbo-charge","turbocharges","tweaks","twitching","ultimate","unadulterated","unassuming","unauthorized","unbelievable","unburdened","uncaring","uncensored","uncertain","uncomfortable","unconditional","uncontrollable","unconventional","uncovered","undeniable","under priced","undercover","underground","underhanded","underused","unexpected","unforgettable","unheard of","unhurried","uninterested","unique","unjustified","unknowingly","unleashed","unlimited","unlock","unparalleled","unpopular","unreliable","unresponsive","unseen","unstable","unstoppable","unsure","unsurpassed","untapped","unusual","up-sell","upbeat","uplifted","uplifting","urge","urgent","useful","useless","validate","valor","valuable","value","vanquish","vaporize","venomous","verify","vibrant","vicious","victim","victory","vigorous","vilified","vindictive","violated","violent","volatile","vulnerable","waiting","wanted","wanton","warning","waste","weak","wealth","weird","what no one tells you","whip","whopping","wicked","wild","willpower","withheld","wonderful","wondrous","woozy","world","worry","worst","worthwhile","wounded","wreaking","youthful","zen","zinger"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":true,"hasBreadcrumb":true},"homeUrl":"https:\/\/queendentaireturquie.com\/en\/","objectID":1153,"objectType":"post","locale":"en","localeFull":"en_US","overlayImages":{"play":{"name":"Play icon","url":"https:\/\/queendentaireturquie.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/home\/u286762492\/domains\/queendentaireturquie.com\/public_html\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"GIF icon","url":"https:\/\/queendentaireturquie.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/home\/u286762492\/domains\/queendentaireturquie.com\/public_html\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/queendentaireturquie.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/social-placeholder.jpg","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Fqueendentaireturquie.com%2Fen%2F&r=https%3A%2F%2Fqueendentaireturquie.com%2Fen%2Fwp-json%2Fwp%2Fv2%2Fpages%2F1153%3Fnonce%3D4b8e6a9b06&pro=1","maxTags":100,"trendsIcon":"<svg width=\"100%\" height=\"100%\" viewBox=\"0 0 36 36\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" fit=\"\" preserveAspectRatio=\"xMidYMid meet\" focusable=\"false\">\n\t\t<g id=\"Page-1\" stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t<g id=\"Trends-Arrow\">\n\t\t\t\t<g id=\"TrendsArrow\">\n\t\t\t\t\t<path d=\"M1.11227159,26.3181534 L10.2875029,17.1429221 L13.7152617,20.5706809 L4.5400304,29.7459122 C4.20518633,30.0807563 3.66229681,30.0807562 3.32745277,29.7459122 L1.11136262,27.529822 C0.776518575,27.194978 0.776518548,26.6520885 1.11136262,26.3172444 L1.11227159,26.3181534 Z\" id=\"Shape\" fill=\"#4285F4\" fill-rule=\"nonzero\"><\/path>\n\t\t\t\t\t<path d=\"M14.3201543,14.3211528 L22.283717,22.2847155 L19.4658829,25.1025495 C19.1310388,25.4373936 18.5881494,25.4373937 18.2533053,25.1025495 L10.2906516,17.1398959 L13.1084857,14.3220618 C13.4429747,13.987572 13.9851638,13.9871653 14.3201543,14.3211528 Z\" id=\"Shape\" fill=\"#EA4335\" fill-rule=\"nonzero\"><\/path>\n\t\t\t\t\t<polygon id=\"Rectangle-path\" fill=\"#FABB05\" fill-rule=\"nonzero\" points=\"18.8573051 18.8577571 28.2843236 9.43073862 31.7120824 12.8584974 22.2850639 22.2855159\"><\/polygon>\n\t\t\t\t\t<path d=\"M35.0711567,15.5054713 L35.0711567,7 L35.0711567,7 C35.0711567,6.44771525 34.6234415,6 34.0711567,6 L25.5656854,6 L25.5656854,6 C25.0134007,6 24.5656854,6.44771525 24.5656854,7 C24.5656854,7.26521649 24.6710423,7.5195704 24.8585786,7.70710678 L33.3640499,16.2125781 L33.3640499,16.2125781 C33.7545742,16.6031024 34.3877392,16.6031024 34.7782635,16.2125781 C34.9657999,16.0250417 35.0711567,15.7706878 35.0711567,15.5054713 Z\" id=\"Shape\" fill=\"#34A853\" fill-rule=\"nonzero\"><\/path>\n\t\t\t\t\t<rect id=\"Rectangle-path\" x=\"0\" y=\"0\" width=\"36\" height=\"36\"><\/rect>\n\t\t\t\t<\/g>\n\t\t\t<\/g>\n\t\t<\/g>\n\t<\/svg>","showScore":true,"siteFavIcon":"https:\/\/queendentaireturquie.com\/wp-content\/uploads\/2022\/04\/favicon.png","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"isPro":true,"is_front_page":false,"trendsUpgradeLink":"https:\/\/queendentaireturquie.com\/wp-admin\/admin.php?page=rank-math&view=help","trendsUpgradeLabel":"Activate now","trendsPreviewImage":"https:\/\/queendentaireturquie.com\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["a cut above","absolute","absolutely","absolutely lowest","absurd","abuse","accurate","accuse","achieve","actionable","adaptable","adequate","admit","adorable","advantage","advice","affordable","aggravate","aggressive","agitated","agonizing","agony","alarmed","alarming","alienated","aligned","alive","all-inclusive","alluring","always","amazing","amp","animated","annihilate","announcing","anonymous","antagonistic","anxious","apocalypse","appalled","approved","approving","argumentative","armageddon","arrogant","ass kicking","assault","assured","astonishing","astounded","astounding","at ease","atrocious","attack","attractive","audacity","authentic","authoritative","authority","avoid","aware","awe-inspiring","awesome","awkward","backbone","backdoor","backed","backlash","backstabbing","badass","balanced","banned","bargain","barrage","basic","battle","beaming","beat down","beating","beautiful","beauty","begging","behind the scenes","belief","belong","best","best-selling","better","beware","big","billion","black market","blacklisted","blast","blessed","blinded","blissful","blood","bloodbath","bloodcurdling","bloody","blunder","blushing","bold","bomb","bona","bona fide","bonanza","bonus","bootleg","bottom line","bountiful","brave","bravery","brazen","break","breaking","breakthrough","breathtaking","bright","brilliant","broke","brutal","budget","buffoon","bullshit","bully","bumbling","buy","cadaver","calm","cancel anytime","capable","captivate","captivating","carefree","case study","cash","cataclysmic","catapult","catastrophe","caution","censored","centered","certain","certainly","certified","challenge","charming","cheap","cheat","cheat-sheet","cheer","cheerful","child-like","clarity","classified","clear","clueless","collapse","colorful","colossal","comfortable","compare","competitive","complete","completely","completeness","comprehensive","compromise","compulsive","concealed","conclusive","condemning","condescending","confess","confession","confessions","confident","confidential","conquer","conscientious","constructive","content","contrary","controlling","controversial","convenient","convert","cool","cooperative","copy","corpse","corrupt","corrupting","courage","courageous","cover-up","covert","coward","cowardly","crammed","crave","crazy","create","creative","cringeworthy","cripple","crisis","critical","crooked","crush","crushing","damaging","danger","dangerous","daring","dazzling","dead","deadline","deadly","death","decadent","deceived","deceptive","deep","defiance","definitely","definitive","defying","dejected","delicious","delight","delighted","delightful","delirious","delivered","demoralizing","deplorable","depraved","desire","desperate","despicable","destiny","destroy","detailed","devastating","devoted","diagnosed","direct","dirty","disadvantages","disastrous","discount","discover","disdainful","disempowered","disgusted","disgusting","dishonest","disillusioned","disoriented","distracted","distraught","distressed","distrustful","divulge","document","dollar","dominate","doomed","double","doubtful","download","dreadful","dreamy","drive","drowning","dumb","dynamic","eager","earnest","easily","easy","economical","ecstatic","edge","effective","efficient","effortless","elated","eliminate","elite","embarrass","embarrassed","embarrassing","emergency","emerging","emphasize","empowered","enchant","encouraged","endorsed","energetic","energy","enormous","enraged","enthusiastic","envy","epic","epidemic","essential","ethical","euphoric","evil","exactly","exasperated","excellent","excited","excitement","exciting","exclusive","exclusivity","excruciating","exhilarated","expensive","expert","explode","exploit","explosive","exposed","exquisite","extra","extraordinary","extremely","exuberant","eye-opening","fail","fail-proof","failure","faith","famous","fantasy","fascinating","fatigued","faux","faux pas","fearless","feast","feeble","festive","fide","fierce","fight","final","fine","fired","first","first ever","flirt","fluid","focus","focused","fool","fooled","foolish","forbidden","force-fed","forever","forgiving","forgotten","formula","fortune","foul","frantic","free","freebie","freedom","frenzied","frenzy","frightening","frisky","frugal","frustrated","fulfill","fulfilled","full","fully","fun","fun-loving","fundamentals","funniest","funny","furious","gambling","gargantuan","genius","genuine","gift","gigantic","giveaway","glamorous","gleeful","glorious","glowing","goddamn","gorgeous","graceful","grateful","gratified","gravity","great","greatest","greatness","greed","greedy","gripping","grit","grounded","growth","guaranteed","guilt","guilt-free","gullible","guts","hack","happiness","happy","harmful","harsh","hate","have you heard","havoc","hazardous","healthy","heart","heartbreaking","heartwarming","heavenly","hell","helpful","helplessness","hero","hesitant","hidden","high tech","highest","highly effective","hilarious","hoak","hoax","honest","honored","hope","hopeful","horribly","horrific","horrifying","horror","hostile","how to","huge","humility","humor","hurricane","hurry","hypnotic","idiot","ignite","illegal","illusive","imagination","immediately","imminently","impatience","impatient","impenetrable","important","impressive","improved","in the zone","incapable","incapacitated","incompetent","inconsiderate","increase","incredible","indecisive","indulgence","indulgent","inexpensive","inferior","informative","infuriated","ingredients","innocent","innovative","insane","insecure","insider","insidious","inspired","inspiring","instant savings","instantly","instructive","insult","intel","intelligent","intense","interesting","intriguing","introducing","invasion","investment","iron-clad","ironclad","irresistible","irs","is here","jackpot","jail","jaw-dropping","jealous","jeopardy","jittery","jovial","joyous","jubilant","judgmental","jumpstart","just arrived","keen","kickass","kickstart","kill","killed","killing","kills","know it all","lame","largest","lascivious","last","last chance","last minute","latest","laugh","laughing","launch","launching","lavishly","lawsuit","lazy","left behind","legendary","legitimate","liberal","liberated","lick","lies","life-changing","lifetime","light","lighthearted","likely","limited","literally","little-known","loathsome","lonely","looming","loser","lost","love","lucrative","lunatic","lurking","lust","luxurious","luxury","lying","magic","magical","magnificent","mainstream","malicious","mammoth","manipulative","marked down","massive","master","masterclass","maul","mediocre","meditative","meltdown","memorability","memorable","menacing","mesmerizing","meticulous","mind-blowing","minimalist","miracle","mired","mischievous","misgiving","missing out","mistake","monetize","money","moneyback","moneygrubbing","monumental","most important","motivated","mouth-watering","murder","mystery","nail","naked","natural","naughty","nazi","nest egg","never","new","nightmare","no good","no obligation","no one talks about","no questions asked","no risk","no strings attached","non-controlling","noted","novelty","now","obnoxious","obsessed","obsession","obvious","odd","off-kilter","off-limits","off-the record","offensive","official","okay","on-demand","open-minded","opportunities","optimistic","ordeal","outlawed","outrageousness","outstanding","overcome","overjoyed","overnight","overwhelmed","packed","painful","painless","painstaking","pale","panic","panicked","paralyzed","pas","passionate","pathetic","pay zero","payback","perfect","peril","perplexed","perspective","pessimistic","pioneering","piranha","pitfall","pitiful","placid","plague","played","playful","pleased","pluck","plummet","plunge","poison","poisonous","polarizing","poor","popular","portfolio","pound","powerful","powerless","practical","preposterous","prestige","price","priceless","pride","prison","privacy","private","privileged","prize","problem","productive","professional","profit","profitable","profound","promiscuous","promising","promote","protect","protected","proven","provocative","provoke","psychological","pummel","punch","punish","pus","quadruple","quality","quarrelsome","quick","quick-start","quickly","quiet","radiant","rare","ravenous","rebellious","recession-proof","reckoning","recognized","recommend","recreate","reduced","reflective","refugee","refund","refundable","reject","relaxed","release","relentless","reliable","remarkable","replicate","report","reprimanding","repulsed","repulsive","research","resentful","resourceful","responsible","responsive","rested","restricted","results","retaliating","reveal","revealing","revenge","revengeful","revisited","revolting","revolutionary","reward","rich","ridiculous","risky","riveting","rookie","rowdy","ruin","rules","ruthless","sabotaging","sacred","sadistic","sadly","sadness","safe","safety","sale","sampler","sarcastic","satisfied","savage","savagery","save","savings","savvy","scam","scandal","scandalous","scarce","scared","scary","scornful","scream","searing","secret","secret agenda","secret plot","secrets","secure","security","seductive","seething","seize","selected","self-hating","self-sufficient","sensational","senseless","sensual","serene","seriously","severe","sex","sexy","shaking","shameful","shameless","shaming","shatter","shellacking","shocking","should","shrewd","sick and tired","signs","silly","simple","simplicity","simplified","simplistic","sincere","sinful","sins","six-figure","sizable","sizzle","sizzled","sizzles","sizzling","sizzlingly","skill","skyrocket","slaughter","slave","sleazy","sleeping","sly","smash","smiling","smug","smuggle","smuggled","sneak-peek","sneaky","sniveling","snob","snooty","snotty","soar","soaring","solid","solution","spank","special","spectacular","speedy","spell-binding","spine","spirit","spirited","spiteful","spoiler","spontaneous","spotlight","spunky","squirming","stable","staggering","startling","steady","steal","stealthy","steamy","step-by-step","still","stoic","stop","strange","strangle","strategy","stressed","strong","strongly suggest","struggle","stuck up","studies","stunning","stupid","stupid-simple","sturdy","sublime","succeed","success","successful","suck","suddenly","suffer","sunny","super","super-human","superb","supercharge","superior","supported","supportive","sure","sure fire","surefire","surge","surging","surprise","surprised","surprising","survival","survive","suspicious","sweaty","swoon","swoon-worthy","tailspin","tank","tantalizing","targeted","tawdry","tease","technology","teetering","tempting","tenacious","tense","terrible","terrific","terrified","terrifying","terror","terrorist","tested","thankful","the truth","threaten","threatened","thrilled","thrilling","thug","ticked off","tickled","timely","today","torture","toxic","track record","trade secret","tragedy","tragic","transform","transparency","trap","trapped","trauma","traumatized","treacherous","treasure","tremendous","trend","tricks","triggers","triple","triumph","truly","trusting","trustworthy","truth","truthful","turbo-charge","turbocharges","tweaks","twitching","ultimate","unadulterated","unassuming","unauthorized","unbelievable","unburdened","uncaring","uncensored","uncertain","uncomfortable","unconditional","uncontrollable","unconventional","uncovered","undeniable","under priced","undercover","underground","underhanded","underused","unexpected","unforgettable","unheard of","unhurried","uninterested","unique","unjustified","unknowingly","unleashed","unlimited","unlock","unparalleled","unpopular","unreliable","unresponsive","unseen","unstable","unstoppable","unsure","unsurpassed","untapped","unusual","up-sell","upbeat","uplifted","uplifting","urge","urgent","useful","useless","validate","valor","valuable","value","vanquish","vaporize","venomous","verify","vibrant","vicious","victim","victory","vigorous","vilified","vindictive","violated","violent","volatile","vulnerable","waiting","wanted","wanton","warning","waste","weak","wealth","weird","what no one tells you","whip","whopping","wicked","wild","willpower","withheld","wonderful","wondrous","woozy","world","worry","worst","worthwhile","wounded","wreaking","youthful","zen","zinger"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":true,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Accueil","robots":{"index":true},"advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"unordered"},"_links":{"self":[{"href":"https:\/\/queendentaireturquie.com\/en\/wp-json\/wp\/v2\/pages\/1153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/queendentaireturquie.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/queendentaireturquie.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/queendentaireturquie.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/queendentaireturquie.com\/en\/wp-json\/wp\/v2\/comments?post=1153"}],"version-history":[{"count":0,"href":"https:\/\/queendentaireturquie.com\/en\/wp-json\/wp\/v2\/pages\/1153\/revisions"}],"wp:attachment":[{"href":"https:\/\/queendentaireturquie.com\/en\/wp-json\/wp\/v2\/media?parent=1153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/queendentaireturquie.com\/en\/wp-json\/wp\/v2\/categories?post=1153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/queendentaireturquie.com\/en\/wp-json\/wp\/v2\/tags?post=1153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}